{"id":37689,"date":"2026-07-15T09:37:18","date_gmt":"2026-07-15T12:37:18","guid":{"rendered":"https:\/\/radioimprensa.com.br\/?p=37689"},"modified":"2026-07-15T09:41:31","modified_gmt":"2026-07-15T12:41:31","slug":"ceos-da-multinacional-japonesa-canon-anunciam-dois-fotografos-renomados-como-embaixadores-da-marca","status":"publish","type":"post","link":"https:\/\/radioimprensa.com.br\/index.php\/2026\/07\/15\/ceos-da-multinacional-japonesa-canon-anunciam-dois-fotografos-renomados-como-embaixadores-da-marca\/","title":{"rendered":"CEOs DA MULTINACIONAL JAPONESA CANON ANUNCIAM DOIS FOT\u00d3GRAFOS RENOMADOS COMO EMBAIXADORES DA MARCA"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A Canon Brasil, l\u00edder no desenvolvimento de tecnologia e solu\u00e7\u00f5es de imagem digital, desde 1974, anunciou a entrada de dois profissionais de destaque em seu programa de embaixadores. O documentarista e fot\u00f3grafo de natureza Jo\u00e3o Paulo Krajewski e o fot\u00f3grafo e diretor de fotografia Pedro Dimitrow passam a integrar o time oficial da marca, refor\u00e7ando a aproxima\u00e7\u00e3o da empresa com o mercado criativo e audiovisual.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O an\u00fancio foi realizado na \u00faltima ter\u00e7a-feira (14) pelos presidentes da multinacional japonesa, Sahun Hizawa e Leo Yamakawa, durante um evento promovido na Casa Canon, em S\u00e3o Paulo. A iniciativa faz parte da estrat\u00e9gia da empresa de valorizar profissionais reconhecidos por sua atua\u00e7\u00e3o na fotografia e na produ\u00e7\u00e3o de imagens.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Jo\u00e3o Paulo Krajewski \u00e9 bi\u00f3logo e doutor em Ecologia pela Universidade Estadual de Campinas (Unicamp), al\u00e9m de ser um dos principais nomes da produ\u00e7\u00e3o de document\u00e1rios sobre a vida selvagem. Em 2025, recebeu o Emmy de Melhor Cinematografia pelo document\u00e1rio Mundo Secreto dos Sons, pr\u00eamio que consolidou sua carreira no cen\u00e1rio internacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">J\u00e1 Pedro Dimitrow re\u00fane mais de tr\u00eas d\u00e9cadas de experi\u00eancia como fot\u00f3grafo e diretor de fotografia. Ao longo da carreira, participou de importantes campanhas publicit\u00e1rias e recebeu premia\u00e7\u00f5es no Brasil e no exterior, tornando-se uma refer\u00eancia no segmento audiovisual.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como novos embaixadores, os dois profissionais ter\u00e3o acesso antecipado aos lan\u00e7amentos de c\u00e2meras, lentes e outros equipamentos da Canon. Tamb\u00e9m produzir\u00e3o conte\u00fados utilizando as tecnologias da marca, participar\u00e3o de eventos e compartilhar\u00e3o experi\u00eancias e avalia\u00e7\u00f5es que poder\u00e3o contribuir para o desenvolvimento de futuros produtos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acordo com a Canon Brasil, a chegada de Jo\u00e3o Paulo Krajewski e Pedro Dimitrow refor\u00e7a o compromisso da empresa com a inova\u00e7\u00e3o, a promo\u00e7\u00e3o da troca de conhecimento e o fortalecimento dos la\u00e7os com fot\u00f3grafos, cinegrafistas e criadores de conte\u00fado em todo o pa\u00eds.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Canon Brasil, l\u00edder no desenvolvimento de tecnologia e solu\u00e7\u00f5es de imagem digital, desde 1974, anunciou a entrada de dois profissionais de destaque em seu programa de embaixadores. O documentarista e fot\u00f3grafo de natureza Jo\u00e3o Paulo Krajewski e o fot\u00f3grafo e diretor de fotografia Pedro Dimitrow passam a integrar o time oficial da marca, refor\u00e7ando &hellip; <\/p>\n","protected":false},"author":1,"featured_media":37688,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-37689","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/radioimprensa.com.br\/index.php\/wp-json\/wp\/v2\/posts\/37689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radioimprensa.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radioimprensa.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radioimprensa.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radioimprensa.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=37689"}],"version-history":[{"count":3,"href":"https:\/\/radioimprensa.com.br\/index.php\/wp-json\/wp\/v2\/posts\/37689\/revisions"}],"predecessor-version":[{"id":37692,"href":"https:\/\/radioimprensa.com.br\/index.php\/wp-json\/wp\/v2\/posts\/37689\/revisions\/37692"}],"wp:attachment":[{"href":"https:\/\/radioimprensa.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=37689"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radioimprensa.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=37689"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radioimprensa.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=37689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}